{"id":20074,"date":"2026-03-04T06:45:35","date_gmt":"2026-03-04T06:45:35","guid":{"rendered":"https:\/\/prensaregionalhuaraz.com.pe\/?p=20074"},"modified":"2026-03-04T06:45:35","modified_gmt":"2026-03-04T06:45:35","slug":"candidata-al-senado-impulsa-ley-del-latigo-contra-corruptos-si-probaran-unito-de-esto-los-candidatos-no-vendrian-con-mentiras","status":"publish","type":"post","link":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/2026\/03\/04\/candidata-al-senado-impulsa-ley-del-latigo-contra-corruptos-si-probaran-unito-de-esto-los-candidatos-no-vendrian-con-mentiras\/","title":{"rendered":"Candidata al Senado impulsa \u2018ley del l\u00e1tigo\u2019  contra corruptos: \u201cSi probaran unito de esto los candidatos, no vendr\u00edan con mentiras\u201d"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-20075\" src=\"https:\/\/prensaregionalhuaraz.com.pe\/wp-content\/uploads\/2026\/03\/LEY-DEL-LATIGOOOOO.jpg\" alt=\"\" width=\"482\" height=\"283\" srcset=\"https:\/\/prensaregionalhuaraz.com.pe\/wp-content\/uploads\/2026\/03\/LEY-DEL-LATIGOOOOO.jpg 482w, https:\/\/prensaregionalhuaraz.com.pe\/wp-content\/uploads\/2026\/03\/LEY-DEL-LATIGOOOOO-300x176.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/p>\n<p><strong>Maruja Inquilla, quien busca llegar al Senado por el partido Dem\u00f3crata Verde, present\u00f3 su controvertida propuesta para conseguir justicia y combatir la corrupci\u00f3n con un \u201ccastigo ancestral\u201d.<\/strong><\/p>\n<p><strong>\u00a0Este l\u00e1tigo cae una y corrige. Porque con esto no se mata (&#8230;) Por eso, el que pruebe esto no miente, no enga\u00f1a y no es corrupto\u201d<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>(Olenka Preciado &#8211; larepublica.pe)<\/strong><\/p>\n<p><strong>Maruja Inquilla, candidata al Senado por el partido Dem\u00f3crata Verde, se present\u00f3 en el programa \u2018Sin guion\u2019 acompa\u00f1ada de un l\u00e1tigo al que llam\u00f3 \u201ccastigo ancestral\u201d, el cual busca impulsar para erradicar la corrupci\u00f3n a trav\u00e9s de la \u201cley del l\u00e1tigo\u201d, debido a que en \u201cnuestro pa\u00eds no hay justicia\u201d. \u201cY prueba uno, y se acordar\u00e1 de que no vuelve a ser m\u00e1s corrupto. <\/strong><\/p>\n<p><strong>Eso es lo que falta promover, falta m\u00e1s chicote&#8230; Si probaran unito de esto los candidatos que ahora se comprometen, no vendr\u00edan as\u00ed con mentiras\u201d, argument\u00f3. <\/strong><\/p>\n<p><strong>\u201cDefinitivamente, con los asesinatos, sicariatos, tanto abuso, tanta mentira, tanta corrupci\u00f3n, es peor el da\u00f1o de lo que este l\u00e1tigo te hace. <\/strong><\/p>\n<p><strong>Este l\u00e1tigo cae una y corrige. Porque con esto no se mata (&#8230;) Por eso, el que pruebe esto no miente, no enga\u00f1a y no es corrupto\u201d, agreg\u00f3 Inquilla.<\/strong><\/p>\n<p><strong>La tambi\u00e9n activista ambiental revel\u00f3 haber sido cercana a Pedro Castillo e incluso tenido comunicaci\u00f3n \u201cpermanente\u201d con Dina Boluarte antes que asumiera como presidenta.<\/strong><\/p>\n<p><strong>\u00a0Sin embargo, ante el pedido que le hiciera la exmandataria de convocar a l\u00edderes de su regi\u00f3n (Puno) para que la apoyen al inicio de su gobierno, Inquilla mostr\u00f3 su fuerte rechazo a esta situaci\u00f3n y convoc\u00f3 a la gente de su pueblo para movilizarse en contra de ella.<\/strong><\/p>\n<p><strong>\u201cYo sab\u00eda que Dina Boluarte lo que pretend\u00eda era sacarlo (a Castillo), sab\u00eda eso perfectamente porque ya antes me hab\u00eda dicho\u2026 por eso es que ella se comunicaba permanentemente conmigo. Dina Boluarte ya estaba preparando a la gente, y eso le dije yo a su cercan\u00eda, incluso al hermano de Pedro Castillo, le comuniqu\u00e9 al que est\u00e1 yendo ahora para el Senado, y escuch\u00f3 y no me crey\u00f3\u201d, relat\u00f3 la aspirante a senadora.<\/strong><\/p>\n<p><strong>Asimismo, coment\u00f3 que se identifica como una \u201camante de la naturaleza\u201d, motivo por el que se inclin\u00f3 por esta agrupaci\u00f3n de tendencia ecologista y no por las otras que tambi\u00e9n la habr\u00edan invitado a formar parte de ellas. <\/strong><\/p>\n<p><strong>\u201cYo les agradezco por esa invitaci\u00f3n, pero como he sido invitada por los ocho partidos pol\u00edticos que ahorita est\u00e1n encabezando; entonces, yo los he rechazado porque tengo motivos, y por mis principios y valores no pod\u00eda aceptar.<\/strong><\/p>\n<p><strong>\u00a0Si no hubiera existido el partido ecologista, le aseguro que yo no hubiera participado\u201d, finaliz\u00f3 Inquilla.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maruja Inquilla, quien busca llegar al Senado por el partido Dem\u00f3crata Verde, present\u00f3 su controvertida propuesta para conseguir justicia y combatir la corrupci\u00f3n con un \u201ccastigo ancestral\u201d. \u00a0Este l\u00e1tigo cae una y corrige. Porque con esto no se mata (&#8230;) Por eso, el que pruebe esto no miente, no enga\u00f1a y no es corrupto\u201d \u00a0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20075,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-20074","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-ancash","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/wp-json\/wp\/v2\/posts\/20074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/wp-json\/wp\/v2\/comments?post=20074"}],"version-history":[{"count":1,"href":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/wp-json\/wp\/v2\/posts\/20074\/revisions"}],"predecessor-version":[{"id":20076,"href":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/wp-json\/wp\/v2\/posts\/20074\/revisions\/20076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/wp-json\/wp\/v2\/media\/20075"}],"wp:attachment":[{"href":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/wp-json\/wp\/v2\/media?parent=20074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/wp-json\/wp\/v2\/categories?post=20074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prensaregionalhuaraz.com.pe\/index.php\/wp-json\/wp\/v2\/tags?post=20074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}